<style type="text/css" data-type="vc_shortcodes-default-css">.vc_do_custom_heading{margin-bottom:0.625rem;margin-top:0;}</style><style type="text/css" data-type="vc_shortcodes-custom-css">.vc_custom_1613061141235{margin-top: 20px !important;}.vc_custom_1613061189812{padding-top: 20px !important;padding-bottom: 40px !important;}.vc_custom_1613061309386{margin-top: 0px !important;margin-bottom: 20px !important;padding-top: 0px !important;padding-bottom: 0px !important;}</style>{"id":14577,"date":"2023-04-21T13:38:49","date_gmt":"2023-04-21T17:38:49","guid":{"rendered":"https:\/\/clicketmortar.com\/?page_id=14577"},"modified":"2024-02-15T14:20:08","modified_gmt":"2024-02-15T19:20:08","slug":"our-research","status":"publish","type":"page","link":"https:\/\/clicketmortar.com\/en\/our-research\/","title":{"rendered":"Recherches"},"content":{"rendered":"[vc_row type=&#8221;full_width_background&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; bg_image=&#8221;11961&#8243; bg_position=&#8221;center center&#8221; bg_repeat=&#8221;no-repeat&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;center&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; bg_image_animation=&#8221;none&#8221;][vc_row_inner column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; top_padding=&#8221;15vh&#8221; bottom_padding=&#8221;15vh&#8221; text_align=&#8221;left&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; bg_image_animation=&#8221;none&#8221; enable_animation=&#8221;true&#8221; animation=&#8221;grow-in&#8221; delay=&#8221;500&#8243;][vc_custom_heading text=&#8221;RESEARCH&#8221; font_container=&#8221;tag:h1|font_size:50|text_align:center|color:%23ffffff&#8221; google_fonts=&#8221;font_family:Nunito%3A300%2Cregular%2C700|font_style:400%20regular%3A400%3Anormal&#8221; css_animation=&#8221;fadeIn&#8221; el_class=&#8221;hero-title&#8221;][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row type=&#8221;full_width_background&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; top_padding=&#8221;6%&#8221; bottom_padding=&#8221;1%&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;center&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; id=&#8221;voir&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;padding-4-percent&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;left-right&#8221; centered_text=&#8221;true&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; bg_image_animation=&#8221;none&#8221;][vc_custom_heading text=&#8221;A careful cocktail of expertise and raw talent&#8221; font_container=&#8221;tag:h2|text_align:center|color:%2309308e|line_height:0&#8243; use_theme_fonts=&#8221;yes&#8221; css_animation=&#8221;fadeIn&#8221; el_class=&#8221;h2_portfolio&#8221; el_id=&#8221;recherches-title&#8221;][divider line_type=&#8221;Small Line&#8221; line_alignment=&#8221;center&#8221; line_thickness=&#8221;3&#8243; divider_color=&#8221;extra-color-2&#8243; animate=&#8221;yes&#8221; custom_height=&#8221;100&#8243; custom_line_width=&#8221;120&#8243; delay=&#8221;100&#8243;][vc_column_text css_animation=&#8221;fadeIn&#8221; el_class=&#8221;subtitle_portfolio&#8221;]\n<p style=\"text-align: center;\" data-pm-slice=\"1 1 []\">Our competitive edge stems from our passions: being on the lookout for the latest digital trends, and learning constantly. The good news? We also love teaching: all our findings can be found in our white papers and in our case studies.<\/p>\n[\/vc_column_text][\/vc_column][\/vc_row][vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; top_padding=&#8221;75&#8243; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; bg_image_animation=&#8221;none&#8221;][vc_raw_html]JTVCcG9zdF9ncmlkJTIwaWQlM0QlMjcxNDg3MiUyNyU1RA==[\/vc_raw_html][\/vc_column][\/vc_row][vc_row type=&#8221;full_width_background&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; bg_color=&#8221;rgba(9,48,128,0.05)&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;left-right&#8221; top_margin=&#8221;150px&#8221; bottom_margin=&#8221;150px&#8221; centered_text=&#8221;true&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; bg_image_animation=&#8221;none&#8221;][vc_custom_heading text=&#8221;Our teachers&#8221; font_container=&#8221;tag:h2|text_align:center|color:%23093083&#8243; use_theme_fonts=&#8221;yes&#8221; css_animation=&#8221;fadeIn&#8221;][divider line_type=&#8221;Small Line&#8221; line_alignment=&#8221;center&#8221; line_thickness=&#8221;3&#8243; divider_color=&#8221;extra-color-2&#8243; animate=&#8221;yes&#8221; custom_height=&#8221;30&#8243; custom_line_width=&#8221;120&#8243; delay=&#8221;100&#8243;][carousel script=&#8221;owl_carousel&#8221; desktop_cols=&#8221;3&#8243; desktop_small_cols=&#8221;3&#8243; tablet_cols=&#8221;3&#8243; mobile_cols=&#8221;1&#8243; column_padding=&#8221;0&#8243; enable_animation=&#8221;true&#8221;][item id=&#8221;1700078573553-6&#8243; tab_id=&#8221;1700078573553-5&#8243; title=&#8221;\u00c9l\u00e9ment&#8221;][vc_row_inner column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;left&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; bg_image_animation=&#8221;none&#8221;][vc_raw_html]JTNDZGl2JTIwY2xhc3MlM0QlMjJlbXBsb3llJTIyJTNFJTBBJTNDaW1nJTIwY2xhc3MlM0QlMjJlbXBsb3llQWNjdWVpbEltYWdlJTIyJTIwc3JjJTNEJTI3aHR0cHMlM0ElMkYlMkZjbGlja2V0bW9ydGFyLmNvbSUyRndwLWNvbnRlbnQlMkZ1cGxvYWRzJTJGMjAyMyUyRjExJTJGQ01fRW5zZWlnbmFudHNfTm9zLVJlY2hlcmNoZXNfc3lsdmFpbi1hbW9yb3MucG5nJTI3JTNFJTBBJTNDZGl2JTIwY2xhc3MlM0QlMjJub21FbXBsb3llJTIyJTNFJTNDYiUzRVN5bHZhaW4lMjBBbW9yb3MlM0MlMkZiJTNFJTNDYnIlM0VIRUMlMjBNb250ciVDMyVBOWFsJTNDJTJGZGl2JTNFJTBBJTNDJTJGZGl2JTNF[\/vc_raw_html][\/vc_column_inner][\/vc_row_inner][\/item][item id=&#8221;1700078573697-1&#8243; tab_id=&#8221;1700078573697-0&#8243; title=&#8221;\u00c9l\u00e9ment&#8221;][vc_row_inner column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;left&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; bg_image_animation=&#8221;none&#8221;][vc_raw_html]JTNDZGl2JTIwY2xhc3MlM0QlMjJlbXBsb3llJTIyJTNFJTBBJTNDaW1nJTIwY2xhc3MlM0QlMjJlbXBsb3llQWNjdWVpbEltYWdlJTIyJTIwc3JjJTNEJTI3aHR0cHMlM0ElMkYlMkZjbGlja2V0bW9ydGFyLmNvbSUyRndwLWNvbnRlbnQlMkZ1cGxvYWRzJTJGMjAyMyUyRjExJTJGQ01fRW5zZWlnbmFudHNfTm9zLVJlY2hlcmNoZXNfc29sLXRhbmd1YXkucG5nJTI3JTNFJTBBJTNDZGl2JTIwY2xhc3MlM0QlMjJub21FbXBsb3llJTIyJTNFJTNDYiUzRVNvbCUyMFRhbmd1YXklM0MlMkZiJTNFJTNDYnIlM0VNY0dpbGwlMjBVbml2ZXJzaXR5JTNDJTJGZGl2JTNFJTBBJTNDJTJGZGl2JTNF[\/vc_raw_html][\/vc_column_inner][\/vc_row_inner][\/item][item id=&#8221;1700078573583-5&#8243; tab_id=&#8221;1700078573584-7&#8243; title=&#8221;\u00c9l\u00e9ment&#8221;][vc_row_inner column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;left&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; bg_image_animation=&#8221;none&#8221;][vc_raw_html]JTNDZGl2JTIwY2xhc3MlM0QlMjJlbXBsb3llJTIyJTNFJTBBJTNDaW1nJTIwY2xhc3MlM0QlMjJlbXBsb3llQWNjdWVpbEltYWdlJTIyJTIwc3JjJTNEJTI3aHR0cHMlM0ElMkYlMkZjbGlja2V0bW9ydGFyLmNvbSUyRndwLWNvbnRlbnQlMkZ1cGxvYWRzJTJGMjAyMyUyRjExJTJGQ01fRW5zZWlnbmFudHNfTm9zLVJlY2hlcmNoZXNfQ2FtaWxsZS1HcmFuZ2UucG5nJTI3JTNFJTBBJTNDZGl2JTIwY2xhc3MlM0QlMjJub21FbXBsb3llJTIyJTNFJTNDYiUzRUNhbWlsbGUlMjBHcmFuZ2UlM0MlMkZiJTNFJTNDYnIlM0VIRUMlMjBNb250ciVDMyVBOWFsJTNDJTJGZGl2JTNFJTBBJTNDJTJGZGl2JTNF[\/vc_raw_html][\/vc_column_inner][\/vc_row_inner][\/item][item id=&#8221;1700078573614-2&#8243; tab_id=&#8221;1700078573615-0&#8243; title=&#8221;\u00c9l\u00e9ment&#8221;][vc_row_inner column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;left&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; bg_image_animation=&#8221;none&#8221;][vc_raw_html]JTNDZGl2JTIwY2xhc3MlM0QlMjJlbXBsb3llJTIyJTNFJTBBJTNDaW1nJTIwY2xhc3MlM0QlMjJlbXBsb3llQWNjdWVpbEltYWdlJTIyJTIwc3JjJTNEJTI3aHR0cHMlM0ElMkYlMkZjbGlja2V0bW9ydGFyLmNvbSUyRndwLWNvbnRlbnQlMkZ1cGxvYWRzJTJGMjAyMyUyRjExJTJGQ01fRW5zZWlnbmFudHNfTm9zLVJlY2hlcmNoZXNfQW5uaWUtR3VlcmFyZC5wbmclMjclM0UlMEElM0NkaXYlMjBjbGFzcyUzRCUyMm5vbUVtcGxveWUlMjIlM0UlM0NiJTNFQW5uaWUlMjBHdSVDMyVBOXJhcmQlM0MlMkZiJTNFJTNDYnIlM0VIRUMlMjBNb250ciVDMyVBOWFsJTNDJTJGZGl2JTNFJTBBJTNDJTJGZGl2JTNF[\/vc_raw_html][\/vc_column_inner][\/vc_row_inner][\/item][item id=&#8221;1700078573637-6&#8243; tab_id=&#8221;1700078573637-7&#8243; title=&#8221;\u00c9l\u00e9ment&#8221;][vc_row_inner column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;left&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; bg_image_animation=&#8221;none&#8221;][vc_raw_html]JTNDZGl2JTIwY2xhc3MlM0QlMjJlbXBsb3llJTIyJTNFJTBBJTNDaW1nJTIwY2xhc3MlM0QlMjJlbXBsb3llQWNjdWVpbEltYWdlJTIyJTIwc3JjJTNEJTI3aHR0cHMlM0ElMkYlMkZjbGlja2V0bW9ydGFyLmNvbSUyRndwLWNvbnRlbnQlMkZ1cGxvYWRzJTJGMjAyMyUyRjExJTJGQ01fRW5zZWlnbmFudHNfTm9zLVJlY2hlcmNoZXNfRGVuaXMtTGFyb2NxdWUucG5nJTI3JTNFJTBBJTNDZGl2JTIwY2xhc3MlM0QlMjJub21FbXBsb3llJTIyJTNFJTNDYiUzRURlbmlzJTIwTGFyb2NxdWUlM0MlMkZiJTNFJTNDYnIlM0VIRUMlMjBNb250ciVDMyVBOWFsJTNDJTJGZGl2JTNFJTBBJTNDJTJGZGl2JTNF[\/vc_raw_html][\/vc_column_inner][\/vc_row_inner][\/item][item id=&#8221;1700078573666-0&#8243; tab_id=&#8221;1700078573666-1&#8243; title=&#8221;\u00c9l\u00e9ment&#8221;][vc_row_inner column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;left&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; bg_image_animation=&#8221;none&#8221;][vc_raw_html]JTNDZGl2JTIwY2xhc3MlM0QlMjJlbXBsb3llJTIyJTNFJTBBJTNDaW1nJTIwY2xhc3MlM0QlMjJlbXBsb3llQWNjdWVpbEltYWdlJTIyJTIwc3JjJTNEJTI3aHR0cHMlM0ElMkYlMkZjbGlja2V0bW9ydGFyLmNvbSUyRndwLWNvbnRlbnQlMkZ1cGxvYWRzJTJGMjAyMyUyRjExJTJGQ01fRW5zZWlnbmFudHNfTm9zLVJlY2hlcmNoZXNfSm9oYW5uZS1sYWJyZWNxdWUucG5nJTI3JTNFJTBBJTNDZGl2JTIwY2xhc3MlM0QlMjJub21FbXBsb3llJTIyJTNFJTNDYiUzRUpvYW5uZSUyMExhYnJlY3F1ZSUzQyUyRmIlM0UlM0NiciUzRUhFQyUyME1vbnRyJUMzJUE5YWwlM0MlMkZkaXYlM0UlMEElM0MlMkZkaXYlM0U=[\/vc_raw_html][\/vc_column_inner][\/vc_row_inner][\/item][\/carousel][\/vc_column][\/vc_row][vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; bg_image_animation=&#8221;none&#8221;][vc_row type=&#8221;full_width_background&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; bg_image=&#8221;14437&#8243; bg_position=&#8221;left top&#8221; bg_repeat=&#8221;no-repeat&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; color_overlay=&#8221;#383e47&#8243; overlay_strength=&#8221;0.8&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; top_margin=&#8221;50px&#8221; bottom_margin=&#8221;50px&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; bg_image_animation=&#8221;none&#8221;][vc_row_inner column_margin=&#8221;40px&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;left&#8221;][vc_column_inner column_padding=&#8221;padding-5-percent&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; bg_image_animation=&#8221;none&#8221; enable_animation=&#8221;true&#8221; animation=&#8221;fade-in&#8221;][vc_column_text]\n<h3 style=\"text-transform: uppercase; font-size: 28px; color: white; font-family: 'Nunito Sans';\">CREATIVITY<\/h3>\n<p style=\"color: white; font-family: 'Nunito';\">Our experts have adventurous and creative minds that will make you discover new opportunities and distinguish yourself from your competitors.<\/p>\n[\/vc_column_text][\/vc_column_inner][vc_column_inner column_padding=&#8221;padding-5-percent&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; bg_image_animation=&#8221;none&#8221; enable_animation=&#8221;true&#8221; animation=&#8221;fade-in&#8221; delay=&#8221;150&#8243;][vc_column_text]\n<h3 style=\"text-transform: uppercase; font-size: 28px; color: white; font-family: 'Nunito Sans';\">RIGOR<\/h3>\n<p style=\"color: white; font-family: 'Nunito';\">Every decision made by our experts is based on tests and data: from your targeted campaign audience to the Emoji placed in your ad copy!<\/p>\n[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][vc_row_inner column_margin=&#8221;40px&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;left&#8221;][vc_column_inner column_padding=&#8221;padding-5-percent&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; bg_image_animation=&#8221;none&#8221; enable_animation=&#8221;true&#8221; animation=&#8221;fade-in&#8221; delay=&#8221;300&#8243;][vc_column_text]\n<h3 style=\"text-transform: uppercase; font-size: 28px; color: white; font-family: 'Nunito Sans';\">INNOVATION<\/h3>\n<p style=\"color: white; font-family: 'Nunito';\">While the normal millenial watches a show or a movie, the Click &amp; Mortar expert listens to a podcast to stay up-to-date with the domain&#8217;s innovations.<\/p>\n[\/vc_column_text][\/vc_column_inner][vc_column_inner column_padding=&#8221;padding-5-percent&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; bg_image_animation=&#8221;none&#8221; enable_animation=&#8221;true&#8221; animation=&#8221;fade-in&#8221; delay=&#8221;450&#8243;][vc_column_text]\n<h3 style=\"text-transform: uppercase; font-size: 28px; color: white; font-family: 'Nunito Sans';\">A DYNAMIC TEAM<\/h3>\n<p style=\"color: white; font-family: 'Nunito';\">The contagious energy of our experts flows into your campaigns, your relationship with the digital universe and your results.<\/p>\n[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row]\n[\/vc_column][\/vc_row][vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; bg_image_animation=&#8221;none&#8221;]\n\t\t<div id=\"fws_6a57156b77af1\"  data-column-margin=\"default\" data-midnight=\"dark\"  class=\"wpb_row vc_row-fluid vc_row full-width-section parallax_section\"  style=\"padding-top: 0px; padding-bottom: 0px; \"><div class=\"row-bg-wrap\" data-bg-animation=\"none\" data-bg-animation-delay=\"\" data-bg-overlay=\"false\"><div class=\"inner-wrap row-bg-layer using-image\" ><div class=\"row-bg viewport-desktop using-image lazyload\" data-parallax-speed=\"fixed\" style=\"background-image:inherit; background-position: left top; background-repeat: no-repeat; \" data-bg-image=\"url(https:\/\/clicketmortar.com\/wp-content\/uploads\/2020\/05\/Background2-conseil.svg)\"><\/div><\/div><\/div><div class=\"row_col_wrap_12 col span_12 dark left\">\n\t<div  class=\"vc_col-sm-12 wpb_column column_container vc_column_container col no-extra-padding inherit_tablet inherit_phone \"  data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" >\n\t\t\t<div class=\"wpb_wrapper\">\n\t\t\t\t<div id=\"fws_6a57156b77de9\" data-midnight=\"\" data-column-margin=\"default\" class=\"wpb_row vc_row-fluid vc_row inner_row\"  style=\"padding-top: 200px; padding-bottom: 200px; \"><div class=\"row-bg-wrap\"> <div class=\"row-bg\" ><\/div> <\/div><div class=\"row_col_wrap_12_inner col span_12  left\">\n\t<div style=\"\" class=\"vc_col-sm-6 vc_col-lg-offset-3 vc_col-lg-6 vc_col-md-offset-3 vc_col-md-6 vc_col-sm-offset-0 vc_col-xs-12 conseil-column wpb_column column_container vc_column_container col child_column padding-5-percent inherit_tablet inherit_phone \"  data-using-bg=\"true\" data-padding-pos=\"all\" data-has-bg-color=\"true\" data-bg-color=\"#ffffff\" data-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" ><div class=\"column-bg-overlay-wrap column-bg-layer\" data-bg-animation=\"none\"><div class=\"column-bg-overlay\" style=\"opacity: 1; background-color: #ffffff;\"><\/div><\/div>\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<h2 style=\"color: #093083;text-align: center\" class=\"vc_custom_heading vc_do_custom_heading wpb_animate_when_almost_visible wpb_fadeIn fadeIn vc_custom_1613061141235\" >Need<br \/>\nAdvice?<\/h2><div class=\"divider-wrap\" data-alignment=\"center\"><div style=\"margin-top: 15px; width: 120px; height: 3px; margin-bottom: 15px;\" data-width=\"120px\" data-animate=\"yes\" data-animation-delay=\"100\" data-color=\"extra-color-2\" class=\"divider-small-border\"><\/div><\/div>\n<div class=\"wpb_text_column wpb_content_element  vc_custom_1613061189812\" >\n\t<p style=\"text-align: center; color: #383e47; font-family: 'Nunito'; font-size: 20px; font-weight: 600;\">Our team of experts<br \/>\nis here for you!<\/p>\n<\/div>\n\n\n\n\n<div class=\"wpb_text_column wpb_content_element  wpb_animate_when_almost_visible wpb_fadeIn fadeIn vc_custom_1613061309386\" >\n\t<p><center><a class=\"nectar-button medium customBtn fondClair rouge\" style=\"border-color: #DD4A42; top: 0; font-weight: bold; margin-bottom: 0; color: #093080;\" href=\"https:\/\/clicketmortar.com\/contact\/\">Contact_us<\/a><\/center><\/p>\n<\/div>\n\n\n\n\n\t\t<\/div> \n\t<\/div>\n\t<\/div> \n<\/div><\/div>\n\t\t\t<\/div> \n\t\t<\/div>\n\t<\/div> \n<\/div><\/div>\n<style type=\"text\/css\" data-type=\"rcb-_wpb_shortcodes_custom_css-11476\">.vc_custom_1613061141235{margin-top: 20px !important;}.vc_custom_1613061189812{padding-top: 20px !important;padding-bottom: 40px !important;}.vc_custom_1613061309386{margin-top: 0px !important;margin-bottom: 20px !important;padding-top: 0px !important;padding-bottom: 0px !important;}<\/style><style type=\"text\/css\" data-type=\"rcb-_wpb_post_custom_css-11476\">.conseil-column .vc_column-inner{\n    padding:5%;\n}<\/style>[\/vc_column][\/vc_row]\n","protected":false},"excerpt":{"rendered":"RESEARCH A careful cocktail of expertise and raw talent Our competitive edge stems from our passions: being on the lookout for the latest digital trends, and learning constantly. The good...","protected":false},"author":4,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-14577","page","type-page","status-publish"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.1.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Recherches | Click &amp; Mortar<\/title>\n<meta name=\"description\" content=\"Chez Click &amp; Mortar, on adore partager le fruit de notre exp\u00e9rience. D\u00e9couvrez les fascinants et utiles r\u00e9sultats de nos recherches en marketing num\u00e9rique.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/clicketmortar.com\/en\/our-research\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Recherches | Click &amp; Mortar\" \/>\n<meta property=\"og:description\" content=\"Chez Click &amp; Mortar, on adore partager le fruit de notre exp\u00e9rience. D\u00e9couvrez les fascinants et utiles r\u00e9sultats de nos recherches en marketing num\u00e9rique.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/clicketmortar.com\/en\/our-research\/\" \/>\n<meta property=\"og:site_name\" content=\"Click &amp; Mortar\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ClicketMortar\/\" \/>\n<meta property=\"article:modified_time\" content=\"2024-02-15T19:20:08+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/clicketmortar.com\/wp-content\/uploads\/2021\/04\/cm_opengraph_900x600.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"900\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@ClicketMortar\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutes\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Recherches | Click &amp; Mortar","description":"Chez Click & Mortar, on adore partager le fruit de notre exp\u00e9rience. D\u00e9couvrez les fascinants et utiles r\u00e9sultats de nos recherches en marketing num\u00e9rique.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/clicketmortar.com\/en\/our-research\/","og_locale":"en_US","og_type":"article","og_title":"Recherches | Click &amp; Mortar","og_description":"Chez Click & Mortar, on adore partager le fruit de notre exp\u00e9rience. D\u00e9couvrez les fascinants et utiles r\u00e9sultats de nos recherches en marketing num\u00e9rique.","og_url":"https:\/\/clicketmortar.com\/en\/our-research\/","og_site_name":"Click &amp; Mortar","article_publisher":"https:\/\/www.facebook.com\/ClicketMortar\/","article_modified_time":"2024-02-15T19:20:08+00:00","og_image":[{"width":900,"height":600,"url":"https:\/\/clicketmortar.com\/wp-content\/uploads\/2021\/04\/cm_opengraph_900x600.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@ClicketMortar","twitter_misc":{"Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/clicketmortar.com\/en\/our-research\/","url":"https:\/\/clicketmortar.com\/en\/our-research\/","name":"Recherches | Click &amp; Mortar","isPartOf":{"@id":"https:\/\/clicketmortar.com\/#website"},"datePublished":"2023-04-21T17:38:49+00:00","dateModified":"2024-02-15T19:20:08+00:00","description":"Chez Click & Mortar, on adore partager le fruit de notre exp\u00e9rience. D\u00e9couvrez les fascinants et utiles r\u00e9sultats de nos recherches en marketing num\u00e9rique.","breadcrumb":{"@id":"https:\/\/clicketmortar.com\/en\/our-research\/#breadcrumb"},"inLanguage":"en-CA","potentialAction":[{"@type":"ReadAction","target":["https:\/\/clicketmortar.com\/en\/our-research\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/clicketmortar.com\/en\/our-research\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/clicketmortar.com\/en\/"},{"@type":"ListItem","position":2,"name":"Recherches"}]},{"@type":"WebSite","@id":"https:\/\/clicketmortar.com\/#website","url":"https:\/\/clicketmortar.com\/","name":"Click &amp; Mortar","description":"Entreprendre \u00e0 l&#039;\u00e8re num\u00e9rique","publisher":{"@id":"https:\/\/clicketmortar.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/clicketmortar.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-CA"},{"@type":"Organization","@id":"https:\/\/clicketmortar.com\/#organization","name":"Click & Mortar","url":"https:\/\/clicketmortar.com\/","logo":{"@type":"ImageObject","inLanguage":"en-CA","@id":"https:\/\/clicketmortar.com\/#\/schema\/logo\/image\/","url":"","contentUrl":"","caption":"Click & Mortar"},"image":{"@id":"https:\/\/clicketmortar.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/ClicketMortar\/","https:\/\/x.com\/ClicketMortar","https:\/\/www.linkedin.com\/company\/10788381?trk=prof-exp-company-name","https:\/\/www.youtube.com\/channel\/UC7Sf1F0_CkQmMGre1_3jBIg"]}]}},"_links":{"self":[{"href":"https:\/\/clicketmortar.com\/en\/wp-json\/wp\/v2\/pages\/14577","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/clicketmortar.com\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/clicketmortar.com\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/clicketmortar.com\/en\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/clicketmortar.com\/en\/wp-json\/wp\/v2\/comments?post=14577"}],"version-history":[{"count":0,"href":"https:\/\/clicketmortar.com\/en\/wp-json\/wp\/v2\/pages\/14577\/revisions"}],"wp:attachment":[{"href":"https:\/\/clicketmortar.com\/en\/wp-json\/wp\/v2\/media?parent=14577"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}